{"id":14533,"date":"2023-10-31T04:19:04","date_gmt":"2023-10-31T04:19:04","guid":{"rendered":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg"},"modified":"2023-10-31T04:19:04","modified_gmt":"2023-10-31T04:19:04","slug":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-2","status":"inherit","type":"attachment","link":"https:\/\/redcross.org.vn\/en\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-2","title":{"rendered":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"class_list":["post-14533","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":720,"file":"2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg","filesize":99986,"sizes":{"medium":{"file":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-300x225.jpg","width":300,"height":225,"filesize":23953,"mime_type":"image\/jpeg","source_url":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-300x225.jpg"},"thumbnail":{"file":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-150x150.jpg","width":150,"height":150,"filesize":9352,"mime_type":"image\/jpeg","source_url":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-150x150.jpg"},"medium_large":{"file":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-768x576.jpg","width":768,"height":576,"filesize":103087,"mime_type":"image\/jpeg","source_url":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas-768x576.jpg"},"full":{"file":"gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/redcross.org.vn\/wp-content\/uploads\/2023\/10\/gia-lai-24-billion-vnd-to-support-women-in-the-program-accompanying-women-in-border-areas.jpg","_links":{"self":[{"href":"https:\/\/redcross.org.vn\/en\/wp-json\/wp\/v2\/media\/14533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redcross.org.vn\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/redcross.org.vn\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/redcross.org.vn\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redcross.org.vn\/en\/wp-json\/wp\/v2\/comments?post=14533"}]}}